{"id":12361,"date":"2024-10-17T10:00:40","date_gmt":"2024-10-17T17:00:40","guid":{"rendered":"https:\/\/abcvancouver.ca\/?page_id=12361"},"modified":"2025-10-15T17:52:11","modified_gmt":"2025-10-16T00:52:11","slug":"newsletter-signup","status":"publish","type":"page","link":"https:\/\/abcvancouver.ca\/zh\/newsletter-signup\/","title":{"rendered":"Newsletter Sign Up"},"content":{"rendered":"<div data-elementor-type=\"wp-page\" data-elementor-id=\"12361\" class=\"elementor elementor-12361\" data-elementor-post-type=\"page\">\n\t\t\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-4b72e21 elementor-section-full_width elementor-section-stretched elementor-section-height-default elementor-section-height-default wpr-particle-no wpr-jarallax-no wpr-parallax-no wpr-sticky-section-no\" data-id=\"4b72e21\" data-element_type=\"section\" data-settings=\"{&quot;stretch_section&quot;:&quot;section-stretched&quot;}\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-6f7f771\" data-id=\"6f7f771\" data-element_type=\"column\" data-settings=\"{&quot;background_background&quot;:&quot;slideshow&quot;,&quot;background_slideshow_gallery&quot;:[{&quot;id&quot;:12832,&quot;url&quot;:&quot;https:\\\/\\\/abcvancouver.ca\\\/wp-content\\\/uploads\\\/2024\\\/11\\\/20240915_142940_compressed.jpg&quot;}],&quot;background_slideshow_loop&quot;:&quot;yes&quot;,&quot;background_slideshow_slide_duration&quot;:5000,&quot;background_slideshow_slide_transition&quot;:&quot;fade&quot;,&quot;background_slideshow_transition_duration&quot;:500}\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-6251be8 elementor--h-position-center elementor--v-position-middle elementor-widget elementor-widget-slides\" data-id=\"6251be8\" data-element_type=\"widget\" data-settings=\"{&quot;navigation&quot;:&quot;none&quot;,&quot;transition&quot;:&quot;fade&quot;,&quot;transition_speed&quot;:3000,&quot;autoplay&quot;:&quot;yes&quot;,&quot;autoplay_speed&quot;:5000,&quot;infinite&quot;:&quot;yes&quot;}\" data-widget_type=\"slides.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<div class=\"elementor-swiper\">\n\t\t\t\t\t<div class=\"elementor-slides-wrapper elementor-main-swiper swiper\" role=\"region\" aria-roledescription=\"carousel\" aria-label=\"Slides\" dir=\"ltr\" data-animation=\"\">\n\t\t\t\t<div class=\"swiper-wrapper elementor-slides\">\n\t\t\t\t\t\t\t\t\t\t<div class=\"elementor-repeater-item-db62444 swiper-slide\" role=\"group\" aria-roledescription=\"slide\"><div class=\"swiper-slide-bg\" role=\"img\" aria-label=\"\"><\/div><div class=\"elementor-background-overlay\"><\/div><div class=\"swiper-slide-inner\" ><div class=\"swiper-slide-contents\"><div class=\"elementor-slide-heading\">ABC Vancouver Newsletter<\/div><\/div><\/div><\/div>\t\t\t\t<\/div>\n\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-5dbabb4 elementor-section-boxed elementor-section-height-default elementor-section-height-default wpr-particle-no wpr-jarallax-no wpr-parallax-no wpr-sticky-section-no\" data-id=\"5dbabb4\" data-element_type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-7706c71\" data-id=\"7706c71\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-47f8940 elementor-widget elementor-widget-text-editor\" data-id=\"47f8940\" data-element_type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<h3>Thank you for connecting with the ABC Vancouver Team and community, and for helping ABC continue to deliver for the residents of Vancouver.\u00a0<\/h3>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-5979aca elementor-section-boxed elementor-section-height-default elementor-section-height-default wpr-particle-no wpr-jarallax-no wpr-parallax-no wpr-sticky-section-no\" data-id=\"5979aca\" data-element_type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-25 elementor-top-column elementor-element elementor-element-9f2b4b4\" data-id=\"9f2b4b4\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap\">\n\t\t\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-top-column elementor-element elementor-element-f6a6dca\" data-id=\"f6a6dca\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-cee6d59 elementor-widget__width-initial elementor-widget elementor-widget-shortcode\" data-id=\"cee6d59\" data-element_type=\"widget\" data-widget_type=\"shortcode.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-shortcode\"><script>(function() {\n\twindow.mc4wp = window.mc4wp || {\n\t\tlisteners: [],\n\t\tforms: {\n\t\t\ton: function(evt, cb) {\n\t\t\t\twindow.mc4wp.listeners.push(\n\t\t\t\t\t{\n\t\t\t\t\t\tevent   : evt,\n\t\t\t\t\t\tcallback: cb\n\t\t\t\t\t}\n\t\t\t\t);\n\t\t\t}\n\t\t}\n\t}\n})();\n<\/script><!-- Mailchimp for WordPress v4.10.9 - https:\/\/wordpress.org\/plugins\/mailchimp-for-wp\/ --><form id=\"mc4wp-form-1\" class=\"mc4wp-form mc4wp-form-13993 mc4wp-form-theme mc4wp-form-theme-light\" method=\"post\" data-id=\"13993\" data-name=\"ABC Vancouver Newsletter Sign-up\" action=\"\" ><div class=\"mc4wp-form-fields\"><p>\r\n    <label>\u540d<\/label>\r\n    <input type=\"text\" name=\"FNAME\" placeholder=\"Your First Name\"\r\n    required=\"\">\r\n<\/p>\r\n<p>\r\n    <label>\u59d3<\/label>\r\n    <input type=\"text\" name=\"LNAME\" placeholder=\"Your Last Name\"\r\n    required=\"\">\r\n<\/p>\r\n<p>\r\n\t<label for=\"email\">Email address: \r\n\t\t<input type=\"email\" id=\"email\" name=\"EMAIL\" placeholder=\"Your Email Address\" required>\r\n\t<\/label>\r\n<\/p>\r\n\r\n<p>\r\n\t<input type=\"submit\" value=\"Sign up\">\r\n<\/p><\/div><label style=\"display: none !important;\">\u5982\u679c\u60a8\u662f\u4eba\u7c7b\uff0c\u8bf7\u4e0d\u8981\u586b\u5199\uff1a <input type=\"text\" name=\"_mc4wp_honeypot\" value=\"\" tabindex=\"-1\" autocomplete=\"off\" \/><\/label><input type=\"hidden\" name=\"_mc4wp_timestamp\" value=\"1778631995\" \/><input type=\"hidden\" name=\"_mc4wp_form_id\" value=\"13993\" \/><input type=\"hidden\" name=\"_mc4wp_form_element_id\" value=\"mc4wp-form-1\" \/><div class=\"mc4wp-response\"><\/div><input type=\"hidden\" name=\"trp-form-language\" value=\"zh\"\/><\/form><!-- \/ Mailchimp for WordPress Plugin --><\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-25 elementor-top-column elementor-element elementor-element-ae244af\" data-id=\"ae244af\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap\">\n\t\t\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-bb9879e elementor-section-boxed elementor-section-height-default elementor-section-height-default wpr-particle-no wpr-jarallax-no wpr-parallax-no wpr-sticky-section-no\" data-id=\"bb9879e\" data-element_type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-83e5288\" data-id=\"83e5288\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-fa77872 elementor-widget elementor-widget-spacer\" data-id=\"fa77872\" data-element_type=\"widget\" data-widget_type=\"spacer.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-spacer\">\n\t\t\t<div class=\"elementor-spacer-inner\"><\/div>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<\/div>","protected":false},"excerpt":{"rendered":"<p>ABC Vancouver Newsletter Thank you for connecting with the ABC Vancouver Team and community, and for helping ABC continue to deliver for the residents of Vancouver.\u00a0<\/p>","protected":false},"author":21,"featured_media":0,"parent":0,"menu_order":0,"comment_status":"closed","ping_status":"closed","template":"elementor_header_footer","meta":{"give_campaign_id":0,"footnotes":""},"class_list":["post-12361","page","type-page","status-publish","hentry"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v26.6 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>Newsletter Sign Up - ABC Vancouver<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/abcvancouver.ca\/zh\/newsletter-signup\/\" \/>\n<meta property=\"og:locale\" content=\"zh_CN\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Newsletter Sign Up - ABC Vancouver\" \/>\n<meta property=\"og:description\" content=\"ABC Vancouver Newsletter Thank you for connecting with the ABC Vancouver Team and community, and for helping ABC continue to deliver for the residents of Vancouver.\u00a0\" \/>\n<meta property=\"og:url\" content=\"https:\/\/abcvancouver.ca\/zh\/newsletter-signup\/\" \/>\n<meta property=\"og:site_name\" content=\"ABC Vancouver\" \/>\n<meta property=\"article:modified_time\" content=\"2025-10-16T00:52:11+00:00\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"\u9884\u8ba1\u9605\u8bfb\u65f6\u95f4\" \/>\n\t<meta name=\"twitter:data1\" content=\"1 \u5206\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\/\/abcvancouver.ca\/zh\/newsletter-signup\/\",\"url\":\"https:\/\/abcvancouver.ca\/zh\/newsletter-signup\/\",\"name\":\"Newsletter Sign Up - ABC Vancouver\",\"isPartOf\":{\"@id\":\"https:\/\/abcvancouver.ca\/zh\/#website\"},\"datePublished\":\"2024-10-17T17:00:40+00:00\",\"dateModified\":\"2025-10-16T00:52:11+00:00\",\"breadcrumb\":{\"@id\":\"https:\/\/abcvancouver.ca\/zh\/newsletter-signup\/#breadcrumb\"},\"inLanguage\":\"zh-Hans\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/abcvancouver.ca\/zh\/newsletter-signup\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/abcvancouver.ca\/zh\/newsletter-signup\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\/\/abcvancouver.ca\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Newsletter Sign Up\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/abcvancouver.ca\/zh\/#website\",\"url\":\"https:\/\/abcvancouver.ca\/zh\/\",\"name\":\"ABC Vancouver\",\"description\":\"for A Better City\",\"publisher\":{\"@id\":\"https:\/\/abcvancouver.ca\/zh\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/abcvancouver.ca\/zh\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"zh-Hans\"},{\"@type\":\"Organization\",\"@id\":\"https:\/\/abcvancouver.ca\/zh\/#organization\",\"name\":\"ABC Vancouver\",\"url\":\"https:\/\/abcvancouver.ca\/zh\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"zh-Hans\",\"@id\":\"https:\/\/abcvancouver.ca\/zh\/#\/schema\/logo\/image\/\",\"url\":\"https:\/\/abcvancouver.ca\/wp-content\/uploads\/2020\/07\/ABC-Logo_Full-Colour-No-Van.svg\",\"contentUrl\":\"https:\/\/abcvancouver.ca\/wp-content\/uploads\/2020\/07\/ABC-Logo_Full-Colour-No-Van.svg\",\"caption\":\"ABC Vancouver\"},\"image\":{\"@id\":\"https:\/\/abcvancouver.ca\/zh\/#\/schema\/logo\/image\/\"}}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Newsletter Sign Up - ABC Vancouver","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/abcvancouver.ca\/zh\/newsletter-signup\/","og_locale":"zh_CN","og_type":"article","og_title":"Newsletter Sign Up - ABC Vancouver","og_description":"ABC Vancouver Newsletter Thank you for connecting with the ABC Vancouver Team and community, and for helping ABC continue to deliver for the residents of Vancouver.\u00a0","og_url":"https:\/\/abcvancouver.ca\/zh\/newsletter-signup\/","og_site_name":"ABC Vancouver","article_modified_time":"2025-10-16T00:52:11+00:00","twitter_card":"summary_large_image","twitter_misc":{"\u9884\u8ba1\u9605\u8bfb\u65f6\u95f4":"1 \u5206"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/abcvancouver.ca\/zh\/newsletter-signup\/","url":"https:\/\/abcvancouver.ca\/zh\/newsletter-signup\/","name":"Newsletter Sign Up - ABC Vancouver","isPartOf":{"@id":"https:\/\/abcvancouver.ca\/zh\/#website"},"datePublished":"2024-10-17T17:00:40+00:00","dateModified":"2025-10-16T00:52:11+00:00","breadcrumb":{"@id":"https:\/\/abcvancouver.ca\/zh\/newsletter-signup\/#breadcrumb"},"inLanguage":"zh-Hans","potentialAction":[{"@type":"ReadAction","target":["https:\/\/abcvancouver.ca\/zh\/newsletter-signup\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/abcvancouver.ca\/zh\/newsletter-signup\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/abcvancouver.ca\/"},{"@type":"ListItem","position":2,"name":"Newsletter Sign Up"}]},{"@type":"WebSite","@id":"https:\/\/abcvancouver.ca\/zh\/#website","url":"https:\/\/abcvancouver.ca\/zh\/","name":"ABC\u6e29\u54e5\u534e","description":"for A Better City","publisher":{"@id":"https:\/\/abcvancouver.ca\/zh\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/abcvancouver.ca\/zh\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"zh-Hans"},{"@type":"Organization","@id":"https:\/\/abcvancouver.ca\/zh\/#organization","name":"ABC\u6e29\u54e5\u534e","url":"https:\/\/abcvancouver.ca\/zh\/","logo":{"@type":"ImageObject","inLanguage":"zh-Hans","@id":"https:\/\/abcvancouver.ca\/zh\/#\/schema\/logo\/image\/","url":"https:\/\/abcvancouver.ca\/wp-content\/uploads\/2020\/07\/ABC-Logo_Full-Colour-No-Van.svg","contentUrl":"https:\/\/abcvancouver.ca\/wp-content\/uploads\/2020\/07\/ABC-Logo_Full-Colour-No-Van.svg","caption":"ABC Vancouver"},"image":{"@id":"https:\/\/abcvancouver.ca\/zh\/#\/schema\/logo\/image\/"}}]}},"campaignId":"","_links":{"self":[{"href":"https:\/\/abcvancouver.ca\/zh\/wp-json\/wp\/v2\/pages\/12361","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/abcvancouver.ca\/zh\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/abcvancouver.ca\/zh\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/abcvancouver.ca\/zh\/wp-json\/wp\/v2\/users\/21"}],"replies":[{"embeddable":true,"href":"https:\/\/abcvancouver.ca\/zh\/wp-json\/wp\/v2\/comments?post=12361"}],"version-history":[{"count":28,"href":"https:\/\/abcvancouver.ca\/zh\/wp-json\/wp\/v2\/pages\/12361\/revisions"}],"predecessor-version":[{"id":14060,"href":"https:\/\/abcvancouver.ca\/zh\/wp-json\/wp\/v2\/pages\/12361\/revisions\/14060"}],"wp:attachment":[{"href":"https:\/\/abcvancouver.ca\/zh\/wp-json\/wp\/v2\/media?parent=12361"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}